{"id":15536,"date":"2023-08-25T17:00:34","date_gmt":"2023-08-25T22:00:34","guid":{"rendered":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/?page_id=15536"},"modified":"2023-09-04T13:20:05","modified_gmt":"2023-09-04T18:20:05","slug":"guia-de-autoevaluacion-de-expendio-de-alimentos","status":"publish","type":"page","link":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/index.php\/guia-de-autoevaluacion-de-expendio-de-alimentos\/","title":{"rendered":"Gu\u00eda de Autoevaluaci\u00f3n de Expendio de Alimentos."},"content":{"rendered":"<a href=\"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/wp-content\/uploads\/2023\/09\/Guia-de-autoevaluacion-de-expendio-de-alimentos-1.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">Gu\u00eda de autoevaluaci\u00f3n de expendio de alimentos (1)<\/a>\n<div class=\"sdm_download_item \"><div class=\"sdm_download_item_top\"><div class=\"sdm_download_thumbnail\"><\/div><div class=\"sdm_download_title\">Gu\u00eda de Autoevaluaci\u00f3n de Expendio de Alimentos.<\/div><\/div><div style=\"clear:both;\"><\/div><div class=\"sdm_download_description\"><\/div><div class=\"sdm_download_link\"><span class=\"sdm_download_button\"><a href=\"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/?sdm_process_download=1&download_id=15542\" class=\"sdm_download blue\" title=\"Gu\u00eda de Autoevaluaci\u00f3n de Expendio de Alimentos.\" target=\"_self\">Gu\u00eda autoevaluaci\u00f3n para descarga<\/a><\/span><span class=\"sdm_download_item_count\"><span class=\"sdm_item_count_number\">294<\/span><span class=\"sdm_item_count_string\"> Downloads<\/span><\/span><\/div><\/div><div class=\"sdm_clear_float\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-15536","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/index.php\/wp-json\/wp\/v2\/pages\/15536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/index.php\/wp-json\/wp\/v2\/comments?post=15536"}],"version-history":[{"count":3,"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/index.php\/wp-json\/wp\/v2\/pages\/15536\/revisions"}],"predecessor-version":[{"id":15681,"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/index.php\/wp-json\/wp\/v2\/pages\/15536\/revisions\/15681"}],"wp:attachment":[{"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/index.php\/wp-json\/wp\/v2\/media?parent=15536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}