{"id":42133,"date":"2021-03-31T09:28:25","date_gmt":"2021-03-31T15:28:25","guid":{"rendered":"http:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/?post_type=lp_course&#038;p=42133"},"modified":"2025-02-11T13:33:51","modified_gmt":"2025-02-11T19:33:51","slug":"lineamientos-sanitarios-tatuajes-microblading-micropigmentacion-y-perforaciones","status":"publish","type":"lp_course","link":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/course\/lineamientos-sanitarios-tatuajes-microblading-micropigmentacion-y-perforaciones\/","title":{"rendered":"Lineamientos Sanitarios: Tatuajes y Perforaciones"},"content":{"rendered":"<h3 style=\"text-align: center;\">\u00a1Bienvenido!<br \/>\nLineamientos Sanitarios: Tatuajes, Microblading, Micropigmentaci\u00f3n y Perforaciones.<\/h3>\n<hr \/>\n<p style=\"text-align: justify;\">La Secretar\u00eda de Salud del Estado de Nuevo Le\u00f3n a trav\u00e9s de la Subsecretar\u00eda de Regulaci\u00f3n y Fomento Sanitario, ha desarrollado este curso con el objetivo de presentar las bases y criterios establecidos en la normatividad vigente a prestadores de servicio de Tatuajes, perforaciones y micropigmentaci\u00f3n, para llevar a cabo los tr\u00e1mites necesarios y obtener su tarjeta de control sanitario, as\u00ed como, emitir recomendaciones para disminuir los riesgos asociados a la pr\u00e1ctica de estas actividades.<\/p>\n<p style=\"text-align: justify;\">Al final del curso se aplicar\u00e1 una evaluaci\u00f3n final, de ser promediada con una calificaci\u00f3n igual o mayor a 80% ser\u00e1 acreedor a una constancia que avala los conocimientos adquiridos.<\/p>\n<p>A partir de su inscripci\u00f3n cuenta con 3 semanas para terminar el curso, en caso de no realizarlo su progreso ser\u00e1 eliminado y deber\u00e1 de inscribirse nuevamente.<\/p>\n<p style=\"text-align: justify;\">Cualquier duda, problema o comentario relacionado al curso, puede contactarnos mediante cualquiera de las siguientes v\u00edas:<br \/>\n&#8211; Tel\u00e9fono: (81) 8130-7016<br \/>\n&#8211; e-mail: contacto.regulacionsanitaria@saludnl.gob.mx<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Bienvenido! Lineamientos Sanitarios: Tatuajes, Microblading, Micropigmentaci\u00f3n y Perforaciones. La Secretar\u00eda de Salud del Estado de Nuevo Le\u00f3n a trav\u00e9s de [&hellip;]<\/p>\n","protected":false},"author":96836,"featured_media":42134,"comment_status":"closed","ping_status":"closed","template":"","course_category":[22,24],"course_tag":[],"class_list":["post-42133","lp_course","type-lp_course","status-publish","has-post-thumbnail","hentry","course_category-poblacion-en-general","course_category-sector-productivo","course"],"_links":{"self":[{"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/wp-json\/wp\/v2\/lp_course\/42133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/wp-json\/wp\/v2\/lp_course"}],"about":[{"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/wp-json\/wp\/v2\/types\/lp_course"}],"author":[{"embeddable":true,"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/wp-json\/wp\/v2\/users\/96836"}],"replies":[{"embeddable":true,"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/wp-json\/wp\/v2\/comments?post=42133"}],"version-history":[{"count":0,"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/wp-json\/wp\/v2\/lp_course\/42133\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/wp-json\/wp\/v2\/media\/42134"}],"wp:attachment":[{"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/wp-json\/wp\/v2\/media?parent=42133"}],"wp:term":[{"taxonomy":"course_category","embeddable":true,"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/wp-json\/wp\/v2\/course_category?post=42133"},{"taxonomy":"course_tag","embeddable":true,"href":"https:\/\/saludnl.gob.mx\/regulacion-sanitaria\/cursos\/wp-json\/wp\/v2\/course_tag?post=42133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}